{"id":2057,"date":"2024-08-31T09:42:19","date_gmt":"2024-08-31T09:42:19","guid":{"rendered":"https:\/\/apexes.ac\/?page_id=2057"},"modified":"2024-09-10T09:34:41","modified_gmt":"2024-09-10T09:34:41","slug":"post-graduate","status":"publish","type":"page","link":"https:\/\/apexes.ac\/ar\/post-graduate\/","title":{"rendered":"\u0627\u0644\u062f\u0631\u0627\u0633\u0627\u062a \u0627\u0644\u0639\u0644\u064a\u0627"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2057\" class=\"elementor elementor-2057\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a6c3c4b e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"a6c3c4b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-339d5fa e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"339d5fa\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6fdf77f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"6fdf77f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-858afdb e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"858afdb\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f85bee2 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"f85bee2\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-437cea7 elementor-widget elementor-widget-heading\" data-id=\"437cea7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0627\u0644\u062f\u0631\u0627\u0633\u0627\u062a \u0627\u0644\u0639\u0644\u064a\u0627<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9dc5644 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"9dc5644\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f1bef2 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"7f1bef2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa841f6 elementor-widget elementor-widget-shortcode\" data-id=\"aa841f6\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"post-graduate-courses-wrapper\"><div class=\"apex-course-search-filter\"><input type=\"text\" id=\"apex-graduate-course-search\" class=\"apex-search-bar apex-custom-search-bar\" placeholder=\"\u0627\u062e\u062a\u0631 \u0628\u0631\u0646\u0627\u0645\u062c\u0643 \u0627\u0644\u062f\u0631\u0627\u0633\u064a \u0627\u0644\u0622\u0646!\"><div class=\"apex-filters\"><span class=\"apex-filter-label\">\u062a\u0635\u0641\u064a\u0629<\/span><select id=\"apex-graduate-course-category-filter\" class=\"apex-filter-select\"><option value=\"\" selected>Select University<\/option><option value=\"Al-Eamar University of Guinea\">\u062c\u0627\u0645\u0639\u0629 \u0627\u0644\u0627\u0639\u0645\u0627\u0631 \u063a\u064a\u0646\u064a\u0627<\/option><option value=\"Al-Hikmah University\">\u062c\u0627\u0645\u0639\u0629 \u0627\u0644\u062d\u0643\u0645\u0629<\/option><option value=\"Al-Muhibbah Open University\">\u062c\u0627\u0645\u0639\u0629 \u0627\u0644\u0645\u062d\u0628\u0629 \u0627\u0644\u0645\u0641\u062a\u0648\u062d\u0629<\/option><option value=\"Iconic Open University\">\u062c\u0627\u0645\u0639\u0629 \u0622\u064a\u0643\u0648\u0646\u0643 \u0627\u0644\u0645\u0641\u062a\u0648\u062d\u0629<\/option><option value=\"Nile Valley University\">\u062c\u0627\u0645\u0639\u0629 \u0648\u0627\u062f\u064a \u0627\u0644\u0646\u064a\u0644<\/option><option value=\"Universit\u00e9 de N\u2019Djamena\">\u062c\u0627\u0645\u0639\u0629 \u0623\u0646\u062c\u0645\u064a\u0646\u0627<\/option><\/select><select id=\"apex-graduate-course-language-filter\" class=\"apex-filter-select\"><option value=\"\" selected>Language<\/option><option value=\"English\">English<\/option><option value=\"Arabic\">Arabic<\/option><option value=\"French\">French<\/option><\/select><button class=\"apex-graduate-course-clear-filters\" type=\"button\">\u0623\u0641\u0631\u063a \u0627\u0644\u0645\u062d\u062a\u0648\u064a\u0627\u062a<\/button><\/div><\/div><div class=\"apex-courses-grid\">\r\n    <div  class=\"showNoRecord\" style=\"width:100%\">\r\n        <div  style=\"display:flex; justify-content: center; width:100%;\">\r\n            <div>\r\n                <img loading=\"lazy\" alt=\"no record found\" width=\"300\" height=\"250\" decoding=\"async\" class=\"object-fit-cover\" src=\"https:\/\/apexes.ac\/wp-content\/uploads\/2024\/09\/no-record-found.webp\" \r\n                style=\"color: transparent;\">\r\n                <div style=\"font-size: 30px; font-weight: 600; text-align: center; margin-top: 25px; margin-bottom: 25px;\">No Record Found<\/div>\r\n            <\/div>\r\n            <\/div>\r\n        <\/div><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u062f\u0631\u0627\u0633\u0627\u062a \u0627\u0644\u0639\u0644\u064a\u0627<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"folder":[],"class_list":["post-2057","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/apexes.ac\/ar\/wp-json\/wp\/v2\/pages\/2057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apexes.ac\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/apexes.ac\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/apexes.ac\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apexes.ac\/ar\/wp-json\/wp\/v2\/comments?post=2057"}],"version-history":[{"count":0,"href":"https:\/\/apexes.ac\/ar\/wp-json\/wp\/v2\/pages\/2057\/revisions"}],"wp:attachment":[{"href":"https:\/\/apexes.ac\/ar\/wp-json\/wp\/v2\/media?parent=2057"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/apexes.ac\/ar\/wp-json\/wp\/v2\/folder?post=2057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}